{"id":3165,"date":"2026-07-03T07:56:32","date_gmt":"2026-07-03T05:56:32","guid":{"rendered":"https:\/\/wordpress.nibis.de\/afsos\/?p=3165"},"modified":"2026-08-25T07:14:41","modified_gmt":"2026-08-25T05:14:41","slug":"sommerferien","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/afsos\/sommerferien\/","title":{"rendered":"Sommerferien"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das Schuljahr 2025\/2026 ist Vergangenheit und wir m\u00f6chten uns herzlich bei allen Sch\u00fcler:innen, Eltern und dem Kollegium f\u00fcr ein gro\u00dfartiges Jahr bedanken. Wir w\u00fcnschen Ihnen und Ihren Familien erholsame und sonnige Sommerferien!<\/p>\n\n\n\n<p><br>Wir sehen uns am ersten Schultag (Donnerstag, 13. August 2026) wieder und freuen uns auf ein spannendes neues Schuljahr!\u00a0<br>Die Einschulungsfeier unserer neuen Erstkl\u00e4ssler:innen findet am 14. August 2026 statt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Schuljahr 2025\/2026 ist Vergangenheit und wir m\u00f6chten uns herzlich bei allen Sch\u00fcler:innen, Eltern und dem Kollegium f\u00fcr ein gro\u00dfartiges Jahr bedanken. Wir w\u00fcnschen Ihnen und Ihren Familien erholsame und sonnige Sommerferien! Wir sehen uns am ersten Schultag (Donnerstag, 13. August 2026) wieder und freuen uns auf ein spannendes neues Schuljahr!\u00a0Die Einschulungsfeier unserer neuen Erstkl\u00e4ssler:innen findet am 14. August 2026 statt.<\/p>\n","protected":false},"author":9194704,"featured_media":3166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/posts\/3165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/users\/9194704"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/comments?post=3165"}],"version-history":[{"count":3,"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/posts\/3165\/revisions"}],"predecessor-version":[{"id":3169,"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/posts\/3165\/revisions\/3169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/media\/3166"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/media?parent=3165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/categories?post=3165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/afsos\/wp-json\/wp\/v2\/tags?post=3165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}