{"id":1612,"date":"2017-01-25T15:21:00","date_gmt":"2017-01-25T14:21:00","guid":{"rendered":"http:\/\/wordpress.nibis.de\/awobs\/?p=1612"},"modified":"2017-01-25T15:21:37","modified_gmt":"2017-01-25T14:21:37","slug":"tag-der-offenen-tuer-am-freitag-den-3-februar-2017","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/awobs\/tag-der-offenen-tuer-am-freitag-den-3-februar-2017\/","title":{"rendered":"Tag der offenen T\u00fcr am Freitag, den 3. Februar 2017"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1613\" src=\"http:\/\/wordpress.nibis.de\/awobs\/files\/2017\/01\/T.d.o.T-208x300.png\" alt=\"T.d.o.T\" width=\"208\" height=\"300\" srcset=\"https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/01\/T.d.o.T-208x300.png 208w, https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/01\/T.d.o.T.png 416w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/>Naturwissenschaftliche Experimente, k\u00fcnstlerische Ausstellungen, kulinarisches und Informationen rund um die Oberschule \u2013 das ist nur ein Teil des vielf\u00e4ltigen Programms des diesj\u00e4hrigen Tags der offenen T\u00fcr der Aller-Weser-Oberschule.<\/p>\n<p><strong>Am 3. Februar \u00f6ffnet die Schule in D\u00f6rverden von 14 bis 17.00 Uhr ihre T\u00fcren und zeigt zahlreiche Unterrichts- und Fachr\u00e4ume f\u00fcr alle Interessierten.<\/strong><\/p>\n<p>Sch\u00fcler, Eltern und andere Besucher k\u00f6nnen sich an verschiedenen Stellen \u00fcber die Schule und \u00fcber die Schulform \u201eOberschule\u201c informieren. Hierf\u00fcr stehen die Schulleitung, Lehrer und Sch\u00fclerinnen und Sch\u00fcler bei Schulf\u00fchrungen und der Infopoint in der Mensa zur Verf\u00fcgung.<!--more--><\/p>\n<p>Einen Einblick in die verschiedenen Fachbereiche gibt es an zahlreichen Stellen des Geb\u00e4udes. Es werden sowohl R\u00e4ume und Unterrichtsergebnisse gezeigt als auch Aktionen zum Mitmachen angeboten.<\/p>\n<p>Im Physik- und Chemieraum laden Schau- und Mitmachexperimente zum Verweilen ein. Im Bioraum wird mikroskopiert und seine Kreativit\u00e4t kann man \u00a0im Textilraum mit Servietten unter Beweis stellen. \u00a0Sportliche Aktionen zum Mitmachen werden in der Sporthalle angeboten. Das Fach Deutsch wird sich in der Sch\u00fclerb\u00fccherei pr\u00e4sentieren und die Informatikr\u00e4ume sind ebenfalls ge\u00f6ffnet. Das Projekt der Streitschlichter, der soziale Trainingsraum und der Technikraum werden vorgestellt.<\/p>\n<p>In der Mensa k\u00f6nnen die Besucher beim Kaffeetrinken die Atmosph\u00e4re der Oberschule sp\u00fcren. Auch das Thema \u201eInklusion\u201c bleibt nicht au\u00dfen vor. So ist der F\u00f6rderraum der Oberschule ge\u00f6ffnet, in dem verschiedene Materialien ausgestellt werden.<\/p>\n<p>Der Ganztagsschulbereich wird ebenfalls vertreten sein. So pr\u00e4sentieren sich Arbeitsgemeinschaften wie die\u00a0 orientalischer Tanz AG mit einem Auftritt zu Beginn, die Billard-AG und die Kicker-AG laden zum Spielen ein. Auch die Arbeitsergebnisse der Malen mit Acryl-Farben AG werden ausgestellt.<\/p>\n<p>F\u00fcr das leibliche Wohl sorgen der Schulverein D\u00f6rverden sowie ein Teil der Religionkurse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Naturwissenschaftliche Experimente, k\u00fcnstlerische Ausstellungen, kulinarisches und Informationen rund um die Oberschule \u2013 das ist nur ein Teil des vielf\u00e4ltigen Programms des diesj\u00e4hrigen Tags der offenen T\u00fcr der Aller-Weser-Oberschule. Am 3. Februar \u00f6ffnet die Schule in D\u00f6rverden von 14 bis 17.00 Uhr ihre T\u00fcren und zeigt zahlreiche Unterrichts- und Fachr\u00e4ume f\u00fcr alle Interessierten. Sch\u00fcler, Eltern und [&hellip;]<\/p>\n","protected":false},"author":760,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-1612","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts\/1612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/users\/760"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/comments?post=1612"}],"version-history":[{"count":5,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts\/1612\/revisions"}],"predecessor-version":[{"id":1618,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts\/1612\/revisions\/1618"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/media?parent=1612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/categories?post=1612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/tags?post=1612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}