{"id":1936,"date":"2017-06-07T16:17:41","date_gmt":"2017-06-07T14:17:41","guid":{"rendered":"http:\/\/wordpress.nibis.de\/awobs\/?p=1936"},"modified":"2017-06-17T09:04:20","modified_gmt":"2017-06-17T07:04:20","slug":"die-schule-von-oben","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/awobs\/die-schule-von-oben\/","title":{"rendered":"Die Schule von oben"},"content":{"rendered":"<p><strong>Drohnenbild schafft \u00dcberblick<\/strong><\/p>\n<p>Die Schule bedankt sich bei ihrem ehemaligen Sch\u00fcler Andre Wrigge. Mit seinem Multicopter hatte der Drohnenpilot unl\u00e4ngst ein paar Fotos von dem Schulgel\u00e4nde gemacht und der Schule zur Verf\u00fcgung gestellt.<br \/>\nEin Bildauschnitt ziert jetzt den Header der Schulwebsite. Die komplette Aufnahme und ein weiteres Bild der Schule sieht man hier:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1934\" src=\"http:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image1-300x225.jpg\" alt=\"\" width=\"260\" height=\"195\" srcset=\"https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image1-300x225.jpg 300w, https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image1-768x575.jpg 768w, https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image1.jpg 800w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1937\" src=\"http:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image2-300x225.jpg\" alt=\"\" width=\"258\" height=\"193\" srcset=\"https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image2-300x225.jpg 300w, https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image2-768x575.jpg 768w, https:\/\/wordpress.nibis.de\/awobs\/files\/2017\/06\/image2.jpg 800w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Weitere Aufnahmen und die Galerie &#8222;Geschichte in zwei Augenblicken&#8220;, in der alte Postkartenansichten von D\u00f6rverden in Bilder der Neuzeit eingef\u00fcgt wurden, findet man auf der Website <a href=\"http:\/\/andrair-blog.de\/\">http:\/\/andrair-blog.de\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Drohnenbild schafft \u00dcberblick Die Schule bedankt sich bei ihrem ehemaligen Sch\u00fcler Andre Wrigge. Mit seinem Multicopter hatte der Drohnenpilot unl\u00e4ngst ein paar Fotos von dem Schulgel\u00e4nde gemacht und der Schule zur Verf\u00fcgung gestellt. Ein Bildauschnitt ziert jetzt den Header der Schulwebsite. Die komplette Aufnahme und ein weiteres Bild der Schule sieht man hier: &nbsp; &nbsp; [&hellip;]<\/p>\n","protected":false},"author":760,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-1936","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts\/1936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/users\/760"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/comments?post=1936"}],"version-history":[{"count":6,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts\/1936\/revisions"}],"predecessor-version":[{"id":1956,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/posts\/1936\/revisions\/1956"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/media?parent=1936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/categories?post=1936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/awobs\/wp-json\/wp\/v2\/tags?post=1936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}