{"id":5210,"date":"2022-10-11T12:25:22","date_gmt":"2022-10-11T10:25:22","guid":{"rendered":"https:\/\/wordpress.nibis.de\/cfgs\/?p=5210"},"modified":"2023-01-06T14:46:47","modified_gmt":"2023-01-06T13:46:47","slug":"neue-amateurfunkschulstation-dl0cfg-on-air","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/cfgs\/neue-amateurfunkschulstation-dl0cfg-on-air\/","title":{"rendered":"Neue Amateurfunkschulstation DL0CFG on Air"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p>Endlich ist es soweit, unsere Schule hat eine eigene Amateurfunkschulstation mit dem amtlich zugeteilten Rufzeichen DL0CFG.<br data-rich-text-line-break=\"true\" \/>Der Amateurfunkdienst ist ein gesetzlich geregelter, experimenteller Funkdienst, an dem man nur nach einer bestandenen, offiziellen Pr\u00fcfung bei der Bundesnetzagentur teilnehmen darf. Herr Richardt, als Lehrer an unserer Schule, ist lizenzierter Funkamateur mit dem Rufzeichen DL5AAR und verf\u00fcgt zus\u00e4tzlich \u00fcber ein sogenanntes Ausbildungsrufzeichen. Damit d\u00fcrfen auch Sch\u00fcler<em>innen unserer Schule, unter seiner Aufsicht, am Amateurfunkdienst teilnehmen. Als Antenne h\u00e4ngt auf dem Schulgel\u00e4nde vorerst nur ein langer Draht zwischen den Geb\u00e4uden. Das reicht aus, um weltweit auf Kurzwelle damit zu funken. Langfristig soll die Station auch um eine vhf\/uhf -Station und um eine Satelliten Funkstation erweitert werden. Erste kurze Sprechfunkverbindungen gab es bereits nach Irland, Spanien, Frankreich, Italien und Zypern. Mal sehen, wann es nach Amerika, Afrika, Asien oder Australien klappt. Aktuell gibt es im 7. Jahrgang einen Wahlpflichtkurs Technik \/Amateurfunk, der sich intensiv mit der Materie besch\u00e4ftigt. Bevor die Sch\u00fcler<\/em>innen selbst zum Mikrofon greifen k\u00f6nnen, m\u00fcssen erst noch wichtige \u201eVokabeln\u201c und das internationale Buchstabieralphabet gepaukt werden, um die ordentliche Abwicklung des Funkverkehrs zu gew\u00e4hrleisten.<\/p>\n<p>Bei Interesse und Fragen, kurze Email an Herrn Richardt: frank.richardt(at)cfgs.de senden.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"5212\" src=\"https:\/\/wordpress.nibis.de\/cfgs\/files\/0C1CFAD5-8B56-4CC5-8BD8-F8F24C14692A-640x480.jpeg\" alt=\"\" class=\"wp-image-5212\" srcset=\"https:\/\/wordpress.nibis.de\/cfgs\/files\/0C1CFAD5-8B56-4CC5-8BD8-F8F24C14692A-640x480.jpeg 640w, https:\/\/wordpress.nibis.de\/cfgs\/files\/0C1CFAD5-8B56-4CC5-8BD8-F8F24C14692A-300x225.jpeg 300w, https:\/\/wordpress.nibis.de\/cfgs\/files\/0C1CFAD5-8B56-4CC5-8BD8-F8F24C14692A-768x576.jpeg 768w, https:\/\/wordpress.nibis.de\/cfgs\/files\/0C1CFAD5-8B56-4CC5-8BD8-F8F24C14692A-1536x1152.jpeg 1536w, https:\/\/wordpress.nibis.de\/cfgs\/files\/0C1CFAD5-8B56-4CC5-8BD8-F8F24C14692A-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"5213\" src=\"https:\/\/wordpress.nibis.de\/cfgs\/files\/60A9BDEA-E7F6-44B5-B8EB-2BA94091803E-640x480.jpeg\" alt=\"\" class=\"wp-image-5213\" srcset=\"https:\/\/wordpress.nibis.de\/cfgs\/files\/60A9BDEA-E7F6-44B5-B8EB-2BA94091803E-640x480.jpeg 640w, https:\/\/wordpress.nibis.de\/cfgs\/files\/60A9BDEA-E7F6-44B5-B8EB-2BA94091803E-300x225.jpeg 300w, https:\/\/wordpress.nibis.de\/cfgs\/files\/60A9BDEA-E7F6-44B5-B8EB-2BA94091803E-768x576.jpeg 768w, https:\/\/wordpress.nibis.de\/cfgs\/files\/60A9BDEA-E7F6-44B5-B8EB-2BA94091803E-1536x1152.jpeg 1536w, https:\/\/wordpress.nibis.de\/cfgs\/files\/60A9BDEA-E7F6-44B5-B8EB-2BA94091803E-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Endlich ist es soweit, unsere Schule hat eine eigene Amateurfunkschulstation mit dem amtlich zugeteilten Rufzeichen DL0CFG.<\/p>\n","protected":false},"author":9193666,"featured_media":5213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[26],"tags":[],"class_list":["post-5210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schulaktuelles"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/posts\/5210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/users\/9193666"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/comments?post=5210"}],"version-history":[{"count":2,"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/posts\/5210\/revisions"}],"predecessor-version":[{"id":5303,"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/posts\/5210\/revisions\/5303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/media\/5213"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/media?parent=5210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/categories?post=5210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/cfgs\/wp-json\/wp\/v2\/tags?post=5210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}