{"id":106,"date":"2019-09-25T16:29:15","date_gmt":"2019-09-25T14:29:15","guid":{"rendered":"https:\/\/wordpress.nibis.de\/dich\/?page_id=106"},"modified":"2026-01-26T15:25:49","modified_gmt":"2026-01-26T14:25:49","slug":"aufgaben","status":"publish","type":"page","link":"https:\/\/wordpress.nibis.de\/dich\/aufgaben\/","title":{"rendered":"Aufgaben"},"content":{"rendered":"\n<p>Aufgaben der Wettbewerbsrunde 2025-2026:<\/p>\n<p>Experimente rund um Papier:<br \/><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2026\/01\/Das-ist-Chemie-Aufgaben-und-Hinweise-Niedersachsen-2025_26.pdf\" target=\"_blank\" rel=\"noopener\">Das ist Chemie &#8211; Aufgaben und Hinweise Niedersachsen 2025-2026<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2026\/01\/Das-ist-Chemie-Deckblatt-2025-2026.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Deckblatt<\/strong><\/a>, obligatorisch f\u00fcr jede Einsendung!<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Archiv der alten Aufgaben:<\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2011-2012.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2011-2012<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2012-2013.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2012-2013<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2013-2014.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2013-2014<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2014-2015.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2014-2015<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2015-2016.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2015-2016<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2016-2017.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2016-2017<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2017-2018.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2017-2018<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2018-2019.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2018-2019<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/11\/Das-ist-Chemie-Aufgaben-Niedersachsen-2019-2020.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2019-2020<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2020\/11\/Das-ist-Chemie-Aufgaben-Niedersachsen-2020-2021-1.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2020-2021<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2021\/11\/Das-ist-Chemie-Aufgaben-Niedersachsen-2021-2022.pdf\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2021-2022<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2022\/11\/Das-ist-Chemie-Aufgaben-Niedersachsen-2022-2023.pdf\" target=\"_blank\" rel=\"noopener\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2022-2023<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2023\/10\/Das-ist-Chemie-Aufgaben-Niedersachsen-2023-24.pdf\" target=\"_blank\" rel=\"noopener\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2023-2024<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2024\/11\/Das-ist-Chemie-Aufgaben-Niedersachsen-2024-25.pdf\" target=\"_blank\" rel=\"noopener\">Das ist Chemie &#8211; Aufgaben Niedersachsen 2024-2025<\/a><\/p>\n<p>Zusatzmaterialien zu den Aufgaben:<\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2011-2012.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2011-2012<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2012-2013.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2012-2013<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2013-2014.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2013-2014<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2014-2015.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2014-2015<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2015-2016.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2015-2016<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2016-2017.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2016-2017<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2017-2018.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2017-2018<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-Niedersachsen-2018-2019.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2018-2019<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2019\/10\/Das-ist-Chemie-Informationen-und-Gef%C3%A4hrdungsbeurteilungen-Niedersachsen-2019-2020.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2019-2020<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2020\/11\/Das-ist-Chemie-Informationen-und-Gef\u00e4hrdungsbeurteilungen-Niedersachsen-2020-2021.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2020-2021<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2021\/11\/Das-ist-Chemie-\u2013-Informationen-und-Gefaehrdungsbeurteilungen-Niedersachsen-2021-2022.pdf\">Das ist Chemie &#8211; Informationen Niedersachsen 2021-2022<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2022\/11\/Das-ist-Chemie-Informationen-und-Gefaehrdungsbeurteilungen-Niedersachsen-2022-2023.pdf\" target=\"_blank\" rel=\"noopener\">Das ist Chemie &#8211; Informationen Niedersachsen 2022-2023<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2023\/10\/Das-ist-Chemie-Informationen-und-Gefaehrdungsbeurteilungen-Niedersachsen-2023-2024.pdf\" target=\"_blank\" rel=\"noopener\">Das ist Chemie &#8211; Informationen Niedersachsen 2023-2024<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/dich\/files\/2024\/11\/Das-ist-Chemie-Informationen-und-Gefaehrdungsbeurteilungen-Niedersachsen-2024-25.pdf\" target=\"_blank\" rel=\"noopener\">Das ist Chemie &#8211; Informationen Niedersachsen 2024-2025<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aufgaben der Wettbewerbsrunde 2025-2026: Experimente rund um Papier:Das ist Chemie &#8211; Aufgaben und Hinweise Niedersachsen 2025-2026 Deckblatt, obligatorisch f\u00fcr jede Einsendung! \u00a0 \u00a0 \u00a0 Archiv der alten Aufgaben: Das ist Chemie &#8211; Aufgaben Niedersachsen 2011-2012 Das ist Chemie &#8211; Aufgaben Niedersachsen 2012-2013 Das ist Chemie &#8211; Aufgaben Niedersachsen 2013-2014 Das ist Chemie &#8211; Aufgaben Niedersachsen [&hellip;]<\/p>\n","protected":false},"author":9193089,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-106","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/pages\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/users\/9193089"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":32,"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/pages\/106\/revisions"}],"predecessor-version":[{"id":476,"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/pages\/106\/revisions\/476"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/dich\/wp-json\/wp\/v2\/media?parent=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}