{"id":2287,"date":"2022-11-08T10:30:11","date_gmt":"2022-11-08T09:30:11","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gsahlem\/?p=2287"},"modified":"2022-11-08T10:30:11","modified_gmt":"2022-11-08T09:30:11","slug":"ausstellung-zum-wildniskunst-projekt","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gsahlem\/ausstellung-zum-wildniskunst-projekt\/","title":{"rendered":"Ausstellung zum &#8222;Wildniskunst-Projekt&#8220;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2288 alignleft\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2022\/11\/20221107_161130-225x300.jpg\" alt=\"\" width=\"271\" height=\"361\" srcset=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2022\/11\/20221107_161130-225x300.jpg 225w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2022\/11\/20221107_161130-768x1024.jpg 768w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2022\/11\/20221107_161130-1152x1536.jpg 1152w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2022\/11\/20221107_161130-1536x2048.jpg 1536w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2022\/11\/20221107_161130-scaled.jpg 1920w\" sizes=\"auto, (max-width: 271px) 100vw, 271px\" \/>Unter dem Motto &#8222;Der Natur auf der Spur im st\u00e4dtischen Raum&#8220; wurden durch den Kulturtreff Plantage im Stadtbezirk Ahlem-Badenstedt-Davenstedt, gef\u00f6rdert durch das Programm \u201eStartklar in die Zukunft\u201c, Projekte und Workshops f\u00fcr Kinder und Jugendliche angeboten. Noch bis zum 31. Januar 2023 sind die Fotos, Tonaufnahmen und Objekte aus den Wildniskunst-Projekten im Kulturtreff ausgestellt. An dem Projekt waren auch drei Klassen (3b, 4b, 4c) der Grundschule Ahlem beteiligt, die zur Ausstellungser\u00f6ffnung am 07. November mit ihren Eltern, Geschwistern, Freunden und Lehrkr\u00e4ften eingeladen waren. Neben der Foto-Ausstellung und einigen Objekten aus den Workshops und Projekten gab es einen Film zusehen, in dem FSJlerinnen des Kulturtreffs Fotos und Tonaufnahmen aller Projekte gesammelt und zusammengesetzt haben. In der Werkstatt der Planatege durften die anwesenden Kinder zudem selber noch einmal mit der Frottage-Technik kreativ werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unter dem Motto &#8222;Der Natur auf der Spur im st\u00e4dtischen Raum&#8220; wurden durch den Kulturtreff Plantage im Stadtbezirk Ahlem-Badenstedt-Davenstedt, gef\u00f6rdert durch das Programm \u201eStartklar in die Zukunft\u201c, Projekte und Workshops f\u00fcr Kinder und Jugendliche angeboten. Noch bis zum 31. Januar 2023 sind die Fotos, Tonaufnahmen und Objekte aus den Wildniskunst-Projekten im Kulturtreff ausgestellt. An dem [&hellip;]<\/p>\n","protected":false},"author":9193831,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[15,16],"tags":[],"class_list":["post-2287","post","type-post","status-publish","format-standard","hentry","category-beitraege-2022","category-projekte"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/users\/9193831"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/comments?post=2287"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2287\/revisions"}],"predecessor-version":[{"id":2289,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2287\/revisions\/2289"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/media?parent=2287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/categories?post=2287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/tags?post=2287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}