{"id":2435,"date":"2023-04-25T19:49:17","date_gmt":"2023-04-25T17:49:17","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gsahlem\/?p=2435"},"modified":"2023-04-25T19:50:05","modified_gmt":"2023-04-25T17:50:05","slug":"musik-die-uns-umgibt","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gsahlem\/musik-die-uns-umgibt\/","title":{"rendered":"&#8222;Musik, die uns umgibt&#8220;"},"content":{"rendered":"<p>Die Koala-Klasse 4b nahm am 25.4 an dem Workshop \u201eMusik, die uns umgibt\u201c im Rahmen des KinderKulturAbos teil. Nachdem verschiedene Rhythmen ausprobiert sowie \u00fcber Instrumentenfamilien gesprochen wurde, gingen die Kinder auf die Suche nach Alltagsger\u00e4uschen, welche sp\u00e4ter zu einem Song zusammengesetzt wurden.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2437 alignright\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Workshop-Musik-die-uns-umgibt-300x287.jpeg\" alt=\"\" width=\"360\" height=\"344\" srcset=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Workshop-Musik-die-uns-umgibt-300x287.jpeg 300w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Workshop-Musik-die-uns-umgibt-1024x979.jpeg 1024w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Workshop-Musik-die-uns-umgibt-768x734.jpeg 768w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Workshop-Musik-die-uns-umgibt-1536x1468.jpeg 1536w, https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Workshop-Musik-die-uns-umgibt-2048x1958.jpeg 2048w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/p>\n<p>Passend zu jedem Ger\u00e4usch wurde ein Bild gemalt.<\/p>\n<p>K\u00f6nnt ihr \/ K\u00f6nnen Sie die Ger\u00e4usche den Bildern zuordnen?<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"wp-playlist wp-audio-playlist wp-playlist-light\">\n\t\t\t<div class=\"wp-playlist-current-item\"><\/div>\n\t\t<audio controls=\"controls\" preload=\"none\" width=\"578\"\n\t\t\t><\/audio>\n\t<div class=\"wp-playlist-next\"><\/div>\n\t<div class=\"wp-playlist-prev\"><\/div>\n\t<noscript>\n\t<ol>\n\t\t<li><a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Koalas-4b-Ahlem-25.4.23-Song.mp3'>Koalas 4b Ahlem 25.4.23- Song<\/a><\/li>\t<\/ol>\n\t<\/noscript>\n\t<script type=\"application\/json\" class=\"wp-playlist-script\">{\"type\":\"audio\",\"tracklist\":true,\"tracknumbers\":true,\"images\":true,\"artists\":true,\"tracks\":[{\"src\":\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2023\/04\/Koalas-4b-Ahlem-25.4.23-Song.mp3\",\"type\":\"audio\/mpeg\",\"title\":\"Koalas 4b Ahlem 25.4.23- Song\",\"caption\":\"\",\"description\":\"\\u201eKoalas 4b Ahlem 25.4.23- Song\\u201c.\",\"meta\":{\"length_formatted\":\"1:15\"},\"image\":{\"src\":\"https:\/\/wordpress.nibis.de\/gsahlem\/wp-includes\/images\/media\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\/\/wordpress.nibis.de\/gsahlem\/wp-includes\/images\/media\/audio.svg\",\"width\":48,\"height\":64}}]}<\/script>\n<\/div>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Die Koala-Klasse 4b nahm am 25.4 an dem Workshop \u201eMusik, die uns umgibt\u201c im Rahmen des KinderKulturAbos teil. Nachdem verschiedene Rhythmen ausprobiert sowie \u00fcber Instrumentenfamilien gesprochen wurde, gingen die Kinder auf die Suche nach Alltagsger\u00e4uschen, welche sp\u00e4ter zu einem Song zusammengesetzt wurden. Passend zu jedem Ger\u00e4usch wurde ein Bild gemalt. K\u00f6nnt ihr \/ K\u00f6nnen Sie [&hellip;]<\/p>\n","protected":false},"author":9193831,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[17,16],"tags":[],"class_list":["post-2435","post","type-post","status-publish","format-standard","hentry","category-beitraege-2023","category-projekte"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/users\/9193831"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/comments?post=2435"}],"version-history":[{"count":4,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2435\/revisions"}],"predecessor-version":[{"id":2442,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2435\/revisions\/2442"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/media?parent=2435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/categories?post=2435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/tags?post=2435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}