{"id":2809,"date":"2024-07-16T12:16:13","date_gmt":"2024-07-16T10:16:13","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gsahlem\/?p=2809"},"modified":"2024-07-16T12:20:55","modified_gmt":"2024-07-16T10:20:55","slug":"bundesjugenspiele-und-fit4future-aktionstag","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gsahlem\/bundesjugenspiele-und-fit4future-aktionstag\/","title":{"rendered":"Bundesjugenspiele und fit4future-Aktionstag"},"content":{"rendered":"<p>Auch in diesem Jahr endete das Schuljahr wieder mit allerhand sportlichen Aktionen und Projekten an der Grundschule Ahlem, neben dem Trikottag, dem Bewegungspass sowie dem Stadtradeln veranstaltete die Schule in diesem Jahr die Bundesjugenspiele f\u00fcr den 3. und 4. Jahrgang und den fit4future-Aktionstag f\u00fcr die E-Klassen.<\/p>\n<p>Auf dem Sportplatz des SV Ahlems traten die Kinder des 3. und 4. Jahrgangs in den &#8222;neuen&#8220; Bundesjugenspielen gegen ihre Mitsch\u00fclerinnen und Mitsch\u00fcler ihrer eigenen Klasse im Zonenweitsprung, Zonenweitswurf, Sprint und in der Transportstaffel an. Bei, f\u00fcr den Sommer, k\u00fchlen Temperaturen und feuchtem Wetter wurde mit viel gegenseitiger Anfeuerung und Unterst\u00fctzung gewettstreitet. Am Ende wurden alle mit einer Urkunde (Ehren-, Sieger- oder Teilnahmeurkunde) belohnt.<\/p>\n<p>Gleichzeit fand im Geb\u00e4ude der Schule der fit4future-Aktionstag statt. In jeweils drei Teams pro Klasse traten die Sch\u00fclerinnen und Sch\u00fcler der E-Klassen im Zuckerquiz, im Ern\u00e4hrungsquiz, beim Riechen von verschiedenen Gew\u00fcrzen, im Sackh\u00fcpfen, im Eierlauf, im Dosenwerfen und in einem Zahl-Such-Spiel gegeneinander an. Am Ende wurden auch hier alle Kinder mit einer Urkunde belohnt.<\/p>\n<p style=\"text-align: center\"><em>Wir bedanken uns bei allen Helfenden <\/em><em>&#8211; auf dem Sportplatz und in der Schule &#8211;<\/em><\/p>\n<p style=\"text-align: center\"><em>ohne Ihr Engagement k\u00f6nnen solche tollen Veranstaltungen f\u00fcr die Kinder nicht stattfinden!<\/em><\/p>\n<div class=\"wp-block-image\"><\/div>\n<div class=\"wp-block-image\"><\/div>\n<div class=\"wp-block-image\">\n<div id='gallery-1' class='gallery galleryid-2809 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_094535-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_094535-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Eierlauf\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093954-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093954-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Such-die-Zahl\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093359-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093359-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Zuckerquiz\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093216-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093216-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Dosenwerfen\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093802-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093802-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Riechen\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093900-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093900-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Sackh\u00fcpfen\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_094444-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_094444-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Eierlauf\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093621-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093621-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Ern\u00e4hrungsquiz\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093354-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wordpress.nibis.de\/gsahlem\/files\/2024\/07\/20240619_093354-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Zuckerquiz\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<\/div>\n<div class=\"wp-block-image\"><\/div>\n<div class=\"wp-block-image\"><\/div>\n<div class=\"wp-block-image\"><\/div>\n<div class=\"wp-block-image\"><\/div>\n<div class=\"wp-block-image\"><\/div>\n<div><\/div>\n<div><\/div>\n<div class=\"wp-block-image\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auch in diesem Jahr endete das Schuljahr wieder mit allerhand sportlichen Aktionen und Projekten an der Grundschule Ahlem, neben dem Trikottag, dem Bewegungspass sowie dem Stadtradeln veranstaltete die Schule in diesem Jahr die Bundesjugenspiele f\u00fcr den 3. und 4. Jahrgang und den fit4future-Aktionstag f\u00fcr die E-Klassen. Auf dem Sportplatz des SV Ahlems traten die Kinder [&hellip;]<\/p>\n","protected":false},"author":9193831,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[18,16],"tags":[],"class_list":["post-2809","post","type-post","status-publish","format-standard","hentry","category-beitraege-2024","category-projekte"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/users\/9193831"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/comments?post=2809"}],"version-history":[{"count":4,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2809\/revisions"}],"predecessor-version":[{"id":2820,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/posts\/2809\/revisions\/2820"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/media?parent=2809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/categories?post=2809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsahlem\/wp-json\/wp\/v2\/tags?post=2809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}