{"id":2158,"date":"2026-04-14T05:06:45","date_gmt":"2026-04-14T03:06:45","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gsaos\/?p=2158"},"modified":"2026-04-14T05:06:45","modified_gmt":"2026-04-14T03:06:45","slug":"ganztagsprojekt-an-der-aller-oker-schule-mueden","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gsaos\/ganztagsprojekt-an-der-aller-oker-schule-mueden\/","title":{"rendered":"Ganztagsprojekt an der Aller-Oker-Schule M\u00fcden"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201eDas Leben ist bunt\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Farben, Kreativit\u00e4t und eine wichtige Botschaft standen im Mittelpunkt des Ganztagsprojektes \u201eDas Leben ist bunt\u201c, an dem die Grundschulkinder der AG Kinderrechte mit gro\u00dfer Begeisterung teilnahmen. \u00dcber mehrere Wochen setzten sie sich auf vielf\u00e4ltige Weise mit dem Thema auseinander und lernten dabei vor allem eines: Jeder Mensch ist einzigartig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zu Beginn des Projekts durften die Kinder selbst entscheiden, wie ihr Projekt hei\u00dfen sollte und welche Ideen sie umsetzen wollten. Diese Mitbestimmung sorgte von Anfang an f\u00fcr gro\u00dfe Motivation. In den folgenden Wochen gestalteten die Kinder farbenfrohe Plakate, bastelten kreative K\u00f6pfe mit bunter Wolle und erstellten pers\u00f6nliche Steckbriefe \u00fcber sich selbst. Dabei standen die eigenen St\u00e4rken, Interessen und Besonderheiten im Mittelpunkt.<br>Ein besonderes Highlight war das gemeinsame Backen. \u201eDie Muffins waren richtig lecker und sehr bunt\u201c, waren sich die Kinder einig. Auch bei bunten Gruppenspielen zeigten sie viel Teamgeist und hatten gro\u00dfe Freude an Bewegung und Gemeinschaft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neben den kreativen Angeboten besch\u00e4ftigten sich die Kinder auch mit ernsteren Themen. Sie erfuhren, wie Kinder in anderen L\u00e4ndern zur Schule gehen, und sprachen \u00fcber Gemeinsamkeiten und Unterschiede. Dabei wurde schnell deutlich, dass Vielfalt etwas ganz Normales und Wertvolles ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zum Abschluss gestalteten die Kinder eine eigene Projektmappe f\u00fcr zu Hause, die viele Erinnerungen an die gemeinsame Zeit enth\u00e4lt.<br>Das Projekt machte nicht nur Spa\u00df, sondern st\u00e4rkte auch das Selbstbewusstsein und das Gemeinschaftsgef\u00fchl der Kinder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die wichtigste Erkenntnis nahmen am Ende alle mit:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Das Leben ist bunt \u2013 und genau das macht es besonders.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" class=\"wpa-warning wpa-image-missing-alt size-medium wp-image-2159 alignleft\" src=\"https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-1-300x189.jpg\" alt=\"\" width=\"300\" height=\"189\" data-warning=\"Missing alt text\" srcset=\"https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-1-300x189.jpg 300w, https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-1-100x63.jpg 100w, https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-1.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n<div class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" class=\"wpa-warning wpa-image-missing-alt size-medium wp-image-2160 alignright\" src=\"https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-2-300x161.jpg\" alt=\"\" width=\"300\" height=\"161\" data-warning=\"Missing alt text\" srcset=\"https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-2-300x161.jpg 300w, https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-2-100x54.jpg 100w, https:\/\/wordpress.nibis.de\/gsaos\/files\/2026\/04\/projekt-2.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>\u201eDas Leben ist bunt\u201c Farben, Kreativit\u00e4t und eine wichtige Botschaft standen im Mittelpunkt des Ganztagsprojektes \u201eDas Leben ist bunt\u201c, an dem die Grundschulkinder der AG Kinderrechte mit gro\u00dfer Begeisterung teilnahmen. \u00dcber mehrere Wochen setzten sie sich auf vielf\u00e4ltige Weise mit &hellip; <a href=\"https:\/\/wordpress.nibis.de\/gsaos\/ganztagsprojekt-an-der-aller-oker-schule-mueden\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":937,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2158","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts\/2158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/users\/937"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/comments?post=2158"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts\/2158\/revisions"}],"predecessor-version":[{"id":2161,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts\/2158\/revisions\/2161"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/media?parent=2158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/categories?post=2158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/tags?post=2158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}