{"id":2181,"date":"2026-06-27T06:09:23","date_gmt":"2026-06-27T04:09:23","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gsaos\/?p=2181"},"modified":"2026-06-27T06:09:23","modified_gmt":"2026-06-27T04:09:23","slug":"feuerwehr-zum-anfassen-drittklaesslerinnen-erleben-spannenden-vormittag","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gsaos\/feuerwehr-zum-anfassen-drittklaesslerinnen-erleben-spannenden-vormittag\/","title":{"rendered":"Feuerwehr zum Anfassen: Drittkl\u00e4ssler*innen erleben spannenden Vormittag"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wenn im Sachunterricht der dritten Klassen der Aller-Oker-Schule das Thema \u201eFeuer\u201c auf dem Stundenplan steht, darf ein Besuch bei den Profis nat\u00fcrlich nicht fehlen. So machten sich die Kinder der Klassen 3a, 3b und 3c auf den Weg zur \u00f6rtlichen Feuerwehr in M\u00fcden, wo sie von Marco Fricke und Jan Hustedt begr\u00fc\u00dft wurden. Die beiden hatten an zwei Tagen f\u00fcr jede Klasse ein abwechslungsreiches Programm von rund eineinhalb Stunden vorbereitet und gew\u00e4hrten den Kindern spannende Einblicke in die Arbeit der Einsatzkr\u00e4fte.  <\/p>\n\n\n\n<p>Zun\u00e4chst hie\u00df es: aufmerksam zuh\u00f6ren. In einem theoretischen Teil erfuhren die Sch\u00fcler*innen, wie ein Notruf richtig abgesetzt wird, warum Rauchmelder Leben retten und wie man sich im Brandfall richtig verh\u00e4lt. Auch das sogenannte Feuerdreieck, das die Voraussetzungen f\u00fcr die Entstehung eines Feuers erkl\u00e4rt, wurde anschaulich und kindgerecht erl\u00e4utert. <br \/>Anschlie\u00dfend ging es auf Erkundungstour durch das Feuerwehrhaus. Dabei konnten die Kinder einen Blick hinter die Kulissen werfen und erfahren, wie die Feuerwehrleute im Einsatzfall innerhalb k\u00fcrzester Zeit ausr\u00fccken. <br \/>Richtig spektakul\u00e4r wurde es auf dem Au\u00dfengel\u00e4nde. Dort stellten Marco Fricke und Jan Hustedt ein Hilfeleistungsl\u00f6schgruppenfahrzeug (HLF) mit seiner umfangreichen Ausr\u00fcstung vor. Besonders beeindruckt waren die jungen Besucher*innen von der Vorf\u00fchrung des hydraulischen Rettungsger\u00e4ts: Vor ihren Augen wurde eine Autot\u00fcr durchtrennt und auseinandergespreizt \u2013 so, wie es bei der Rettung eingeklemmter Personen nach Verkehrsunf\u00e4llen n\u00f6tig sein kann. <br \/>Nicht weniger eindrucksvoll war die Demonstration eines Fettbrandes. Anschaulich wurde erkl\u00e4rt, warum Wasser hierbei keinesfalls zum L\u00f6schen verwendet werden darf und welche gef\u00e4hrlichen Folgen dies haben kann. <br \/>Zum Abschluss durften die Drittkl\u00e4ssler*innen selbst aktiv werden. Verschiedene Feuerl\u00f6scher wurden vorgestellt, und jedes Kind konnte unter fachkundiger Anleitung einmal ausprobieren, wie ein Feuerl\u00f6scher bedient wird.<br \/>Am Ende waren sich alle einig: Der Besuch bei der Feuerwehr war nicht nur spannend und beeindruckend, sondern vermittelte auch wichtige Kenntnisse f\u00fcr den Ernstfall. Ein herzliches Dankesch\u00f6n gilt Marco Fricke und Jan Hustedt die den Kindern mit viel Engagement und Geduld die Arbeit der Feuerwehr n\u00e4herbrachten<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn im Sachunterricht der dritten Klassen der Aller-Oker-Schule das Thema \u201eFeuer\u201c auf dem Stundenplan steht, darf ein Besuch bei den Profis nat\u00fcrlich nicht fehlen. So machten sich die Kinder der Klassen 3a, 3b und 3c auf den Weg zur \u00f6rtlichen &hellip; <a href=\"https:\/\/wordpress.nibis.de\/gsaos\/feuerwehr-zum-anfassen-drittklaesslerinnen-erleben-spannenden-vormittag\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":937,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2181","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts\/2181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/users\/937"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/comments?post=2181"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts\/2181\/revisions"}],"predecessor-version":[{"id":2182,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/posts\/2181\/revisions\/2182"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/media?parent=2181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/categories?post=2181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsaos\/wp-json\/wp\/v2\/tags?post=2181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}