{"id":2166,"date":"2024-02-21T16:33:28","date_gmt":"2024-02-21T15:33:28","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/?p=2166"},"modified":"2024-03-05T10:55:07","modified_gmt":"2024-03-05T09:55:07","slug":"ferienbetreuung-der-gemeinde-krummhoern","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/2024\/02\/21\/ferienbetreuung-der-gemeinde-krummhoern\/","title":{"rendered":"Ferienbetreuung der Gemeinde Krummh\u00f6rn"},"content":{"rendered":"<p>Die Gemeinde Krummh\u00f6rn bietet auch 2024 eine Ferienbetreuung f\u00fcr Kinder im Alter von 6 bis 12 Jahren in Zusammenarbeit mit dem Landkreis Aurich an. Die Betreuung findet als Halbtagsangebot von 7.30 h bis 13.30 h im Jugendhaus Pewsum statt.<br \/>\nDas Betreuungsangebot richtet sich an die Familien, bei denen entweder beide Elternteile oder ein alleinerziehendes Elternteil in den jeweiligen Ferien arbeiten m\u00fcssen\/muss.<br \/>\nDie Eltern haben die M\u00f6glichkeit, ihre Kinder wochenweise anzumelden. Der Elternbeitrag je Kind betr\u00e4gt 40,00 \u20ac pro Woche. F\u00fcr Geschwisterkinder sind 25,00 \u20ac zu zahlen. Der Beitrag f\u00fcr Alleinerziehende wird auf 20,00 \u20ac pro Woche\/Kind festgesetzt.<br \/>\nFolgende Betreuungszeiten werden angeboten:<br \/>\nOsterferien: KW 12 (18.03.-22.03.)<br \/>\nSommerferien: KW 26 (24.06.-28.06.), KW 27 (01.07.-05.07.) und KW 28 (08.07.-12.07.)<br \/>\nHerbstferien: KW41 (07.10.-11.10.)<\/p>\n<p>Um die Betreuung verl\u00e4sslich planen zu k\u00f6nnen, ist die verbindliche Anmeldung bis zum 29.02.2024 bei der Gemeinde abzugeben. Die Mindestteilnehmerzahl pro Woche betr\u00e4gt 5 Kinder. Sollte diese Gruppengr\u00f6\u00dfe nicht erreicht werden, wird f\u00fcr diese Woche keine Betreuung angeboten.<br \/>\nF\u00fcr R\u00fcckfragen stehen Ihnen Frau Theessen, Tel. 04923 \/916-161, Email: &#116;h&#x65;e&#x73;&#115;&#x65;&#110;&#x40;&#107;r&#x75;m&#x6d;&#104;&#x6f;&#101;&#x72;&#110;&#x2e;&#100;e zur Verf\u00fcgung.<\/p>\n<p>Bitte beachten Sie, dass nur vollst\u00e4ndige Anmeldeunterlagen ber\u00fccksichtigt werden k\u00f6nnen!<br \/>\nDie erforderlichen Anmeldeunterlagen und den Fragenbogen k\u00f6nnen Sie unter diesem Beitrag herunterladen und ausdrucken.<\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/gsgreetsiel\/files\/2024\/02\/Anmeldung-2024.pdf\">Anmeldung 2024<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/gsgreetsiel\/files\/2024\/02\/Fragebogen-Eltern-Ferienbetreuung.pdf\">Fragebogen Eltern-Ferienbetreuung<\/a><\/p>\n<p><a href=\"https:\/\/wordpress.nibis.de\/gsgreetsiel\/files\/2024\/02\/Ferienbetreuung-in-der-Gemeinde-Krummhoern-2024.pdf\">Ferienbetreuung in der Gemeinde Krummh\u00f6rn 2024<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Gemeinde Krummh\u00f6rn bietet auch 2024 eine Ferienbetreuung f\u00fcr Kinder im Alter von 6 bis 12 Jahren in Zusammenarbeit mit dem Landkreis Aurich an. Die &hellip; <\/p>\n","protected":false},"author":1445,"featured_media":2229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/posts\/2166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/users\/1445"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/comments?post=2166"}],"version-history":[{"count":2,"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/posts\/2166\/revisions"}],"predecessor-version":[{"id":2171,"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/posts\/2166\/revisions\/2171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/media\/2229"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/media?parent=2166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/categories?post=2166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsgreetsiel\/wp-json\/wp\/v2\/tags?post=2166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}