{"id":136,"date":"2018-05-07T23:10:46","date_gmt":"2018-05-07T21:10:46","guid":{"rendered":"http:\/\/wordpress.nibis.de\/gsschmedwolt\/?page_id=136"},"modified":"2022-02-04T14:45:09","modified_gmt":"2022-02-04T13:45:09","slug":"krankmeldungen","status":"publish","type":"page","link":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/organisation\/krankmeldungen\/","title":{"rendered":"Krankmeldungen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-494\" src=\"http:\/\/wordpress.nibis.de\/gsschmedwolt\/files\/2018\/06\/krank.png\" alt=\"\" width=\"281\" height=\"232\" \/><\/p>\n<p style=\"text-align: left\">Falls Ihr Kind aus Krankheitsgr\u00fcnden nicht am Unterricht teilnehmen kann, schreiben Sie bitte eine <strong>E-Mail an den\/die Klassenlehrer*in<\/strong> (vo&#114;&#110;&#97;&#x6d;&#x65;&#x2e;&#x6e;&#x61;ch&#110;&#97;&#109;&#x65;&#x40;&#x73;&#x63;&#x68;ul&#101;&#45;&#117;&#x6e;&#x74;&#x65;&#x72;&#x6d;-r&#101;&#103;&#101;&#x6e;&#x62;&#x6f;&#x67;&#x65;n&#46;&#110;&#101;&#116;) in der Zeit von 7.30 Uhr bis 8.00 Uhr. Nur so kann sichergestellt werden, dass die Lehrkr\u00e4fte vor Unterrichtsbeginn von dem Fehlen Ihres Kindes informiert werden.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Meldung von Infektionskrankheiten<\/strong><\/p>\n<p>Es ist zwingend erforderlich, dass Sie das Sekretariat umgehend informieren, wenn bei Ihrem Kind eine der folgenden Infektionskrankheiten auftritt:<\/p>\n<ul>\n<li>Covid-19<\/li>\n<li>R\u00f6teln<\/li>\n<li>Windpocken<\/li>\n<li>Masern<\/li>\n<li>Mumps<\/li>\n<li>Ringelr\u00f6teln<\/li>\n<li>Zytomegalie (Herpesvirus)<\/li>\n<li>Keuchhusten<\/li>\n<li>Hepatitis A oder B<\/li>\n<li>Grippe (echte Influenza \u2013 kein grippaler Infekt)<\/li>\n<li>Scharlach<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Falls Ihr Kind aus Krankheitsgr\u00fcnden nicht am Unterricht teilnehmen kann, schreiben Sie bitte eine E-Mail an den\/die Klassenlehrer*in (vo&#114;&#110;&#x61;&#x6d;&#x65;&#x2e;na&#99;&#104;&#x6e;&#x61;&#x6d;&#x65;&#64;s&#99;&#104;&#117;&#x6c;&#x65;&#x2d;&#x75;nt&#101;&#114;&#x6d;&#x2d;&#x72;&#x65;ge&#110;&#98;&#x6f;&#x67;&#x65;&#x6e;&#46;n&#101;&#116;) in der Zeit von 7.30 Uhr bis 8.00 Uhr. Nur so kann sichergestellt werden, dass die Lehrkr\u00e4fte vor Unterrichtsbeginn von dem Fehlen Ihres Kindes informiert werden. &nbsp; Meldung von Infektionskrankheiten Es ist zwingend erforderlich, dass Sie [&hellip;]<\/p>\n","protected":false},"author":9192595,"featured_media":0,"parent":35,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full-width.php","meta":{"footnotes":""},"class_list":["post-136","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/pages\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/users\/9192595"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":9,"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/pages\/136\/revisions"}],"predecessor-version":[{"id":3933,"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/pages\/136\/revisions\/3933"}],"up":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/pages\/35"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gsschmedwolt\/wp-json\/wp\/v2\/media?parent=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}