{"id":1396,"date":"2021-03-19T12:08:54","date_gmt":"2021-03-19T11:08:54","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gstostedt\/?p=1396"},"modified":"2021-03-19T12:37:19","modified_gmt":"2021-03-19T11:37:19","slug":"selbsttests","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gstostedt\/selbsttests\/","title":{"rendered":"Selbsttests"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/wordpress.nibis.de\/gstostedt\/files\/2021\/03\/corona-5903129_640.jpg\" alt=\"\" class=\"wp-image-1397\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Liebe Eltern,<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">die Inzidenzwerte steigen leider. Um die pers\u00f6nliche Entwicklung der Sch\u00fclerinnen und Sch\u00fcler zu unterst\u00fctzen und Lernr\u00fcckst\u00e4nde aufzuarbeiten, bleiben die Schulen aber offen. Die Schul\u00f6ffnungen werden nun durch ein umfangreiches Testkonzept begleitet, das dazu beitragen soll, dass die Schule sicherer wird. Deshalb k\u00f6nnen Ihre Kinder demn\u00e4chst jede Woche einmal getestet wer\u00adden. Die Tests sind freiwillig und kostenlos und sollen von Ihrem Kind <strong>zu Hause<\/strong> durchgef\u00fchrt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was ist das f\u00fcr ein Test und wie funktioniert er?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die neuen Tests sind einfach zu bedienen. Sie tun nicht weh und sind nicht unangenehm. F\u00fcr den Test muss man mit einem St\u00e4bchen leicht in der Nase bohren \u2013 aber nicht tief. In anderen L\u00e4ndern gibt es diese Tests f\u00fcr Schulkinder schon l\u00e4nger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bitte erkl\u00e4ren Sie Ihren Kindern, wie wichtig ein solcher Test ist. Nur wenn viele bei den Tests mitmachen, k\u00f6nnen Ansteckungen schnell erkannt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei den Tests handelt es sich um Schnelltests. Man muss nicht lange auf das Ergebnis warten. Die Tests wurden von Experten gepr\u00fcft und zugelassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wer f\u00fchrt den Test durch?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alle Sch\u00fclerinnen und Sch\u00fcler k\u00f6nnen den Test zun\u00e4chst zu Hause selber durchf\u00fchren. Sogar Grundschulkinder k\u00f6nnen das. Es wird den Kindern gezeigt, wie sie das St\u00e4bchen in der Nase bewegen m\u00fcssen. Hier ist ein Video, in dem der Test erkl\u00e4rt wird:<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_12698\" class=\"__youtube_prefs__  __youtube_prefs_gdpr__  epyt-is-override \" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><p><strong>Please accept YouTube cookies to play this video.<\/strong> By accepting you will be accessing content from YouTube, a service provided by an external third party.<\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">YouTube privacy policy<\/a><\/p>\n<p>If you accept this notice, your choice will be saved and the page will refresh.<\/p>\n<button type=\"button\" class=\"__youtube_prefs_gdpr__\">Accept YouTube Content<img decoding=\"async\" src=\"https:\/\/wordpress.nibis.de\/gstostedt\/wp-content\/plugins\/youtube-embed-plus\/images\/icon-check.png\" alt=\"accept\" data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\" \/><\/button><\/div>\n<\/div><figcaption>Sie sehen das Video nicht? <br>Googeln Sie nach: Torben erkl\u00e4rt den Coronatest Hamburg<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wann soll mein Kind sich testen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Tests sollen einmal in der Woche stattfinden, und zwar immer am ersten Schultag der Woche <strong>vor Schulbeginn<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Woher bekomme ich den Test?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Damit Sie den Test zu Hause mit Ihrem Kind durchf\u00fchren k\u00f6nnen, ben\u00f6tigt die Schule Ihr Einverst\u00e4ndnis, denn erst dann erh\u00e4lt Ihr Kind das Testkit f\u00fcr den Corona-Laientest von der Schule. Die Einverst\u00e4ndniserkl\u00e4rung ist als Anlage diesem Schreiben beigef\u00fcgt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was passiert, wenn der Test kein Corona findet?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn der Test kein Zeichen von Corona findet, dann kann das Kind am Unterricht teilnehmen. Es muss aber trotzdem Abstand halten, H\u00e4nde waschen und Maske tragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was passiert, wenn der Test Corona-Viren anzeigt?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn beim Schnelltest Zeichen von Corona-Viren gefunden werden, m\u00fcssen Sie Ihr Kind zu Hause lassen und der Schule sofort Bescheid geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf jeden Fall muss dann ein zweiter Test beim Arzt gemacht werden. Der zweite PCR-Test ist etwas genauer. Die Schule gibt dem Gesundheitsamt Bescheid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beim zweiten Test bekommt man das Ergebnis nicht sofort. Bis zum Ergebnis muss Ihr Kind in Quarant\u00e4ne. Es muss sich also von anderen Kindern und Erwachsenen fernhalten. Es darf die Wohnung nicht verlassen.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Wenn auch beim zweiten Test Corona festgestellt wird, sagt Ihnen das Gesundheitsamt, wie Sie und Ihr Kind sich verhalten m\u00fcssen. Wer Corona hat, darf sich nicht mit anderen Menschen treffen.<\/li><li>Wenn beim zweiten Test kein Corona festgestellt wird, sagen Sie uns bitte Bescheid. Ihr Kind kann dann wieder zur Schule kommen.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weshalb ist es wichtig, an den Tests in der Schule teilzunehmen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Eltern, die Schnelltests in der Schule sollen Menschen finden, die sich noch ganz gesund f\u00fchlen, aber trotzdem schon jemand andern anstecken k\u00f6nnten. So wird die Schule sicherer f\u00fcr alle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihre G. Brinkmann<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anlagen:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/wordpress.nibis.de\/gstostedt\/files\/2021\/03\/MK_Selbsttests_Anlage_M_v01_soe.pdf\" target=\"_blank\">Brief des MK<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/wordpress.nibis.de\/gstostedt\/files\/2021\/03\/MK_Selbsttests_Anlage_L_v01_soe.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Einverst\u00e4ndniserkl\u00e4rung<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Eltern, die Inzidenzwerte steigen leider. Um die pers\u00f6nliche Entwicklung der Sch\u00fclerinnen und Sch\u00fcler zu unterst\u00fctzen und Lernr\u00fcckst\u00e4nde aufzuarbeiten, bleiben die Schulen aber offen. Die Schul\u00f6ffnungen werden nun durch ein umfangreiches Testkonzept begleitet, das dazu beitragen soll, dass die Schule &hellip; <a href=\"https:\/\/wordpress.nibis.de\/gstostedt\/selbsttests\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":9192536,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1396","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/posts\/1396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/users\/9192536"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/comments?post=1396"}],"version-history":[{"count":3,"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/posts\/1396\/revisions"}],"predecessor-version":[{"id":1404,"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/posts\/1396\/revisions\/1404"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/media?parent=1396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/categories?post=1396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gstostedt\/wp-json\/wp\/v2\/tags?post=1396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}