{"id":1207,"date":"2019-08-01T12:09:14","date_gmt":"2019-08-01T10:09:14","guid":{"rendered":"https:\/\/wordpress.nibis.de\/gymoedeme\/?p=1207"},"modified":"2026-08-26T11:51:30","modified_gmt":"2026-08-26T09:51:30","slug":"sicherheit-fuer-ihre-kinder-unsere-schuelerschaft-im-netz","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/gymoedeme\/sicherheit-fuer-ihre-kinder-unsere-schuelerschaft-im-netz\/","title":{"rendered":"Sicherheit f\u00fcr Ihre Kinder &#8211; unsere Sch\u00fclerschaft im Netz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Informationen zum Thema Medien, Gewaltvideos auf Sch\u00fclerhandys, Spiele, Internet usw. findet man&nbsp;<a href=\"http:\/\/www.polizei-beratung.de\/themen-und-tipps\/gefahren-im-internet\/aktion-kinder-sicher-im-netz.html\">HIER<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hilfe von Jugendlichen f\u00fcr Jugendliche: das bietet&nbsp;<a href=\"https:\/\/www.juuuport.de\/beratung\/\">Juuuport<\/a>.<br>Bei Online-Problemen (wie z. B. Cybermobbing, Datenklau oder Onlinesucht) helfen speziell geschulte Medienscouts Jugendlichen weiter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Seite&nbsp;<a href=\"http:\/\/www.klicksafe.de\/\">&#8218;Klicksafe&#8216;<\/a>&nbsp;bietet Tipps sowie aktuelle Informationen zu Chancen und Risiken der Internetnutzung. Es gibt Materialien f\u00fcr den Unterricht oder f\u00fcr Elternabende. Zudem werden kurze Filmspots angeboten, u.a. &#8222;Wo ist Klaus?&#8220;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Eltern beklagen, dass ihnen das n\u00f6tige Hintergrundwissen fehlt, um bei Gespr\u00e4chen rund ums Thema Internet mitreden zu k\u00f6nnen. Auf der Seite&nbsp;<a href=\"http:\/\/www.www-kurs.de\/\">WWW-Kurs<\/a>k\u00f6nnen nicht nur Eltern ihr Wissen auffrischen und erg\u00e4nzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook, Instagram, WhatsApp&#8230; soziale Netzwerke sind mittlerweile ein Muss bei den meisten Sch\u00fclern. Wie viele Daten gebe ich eigentlich dadurch von mir preis? Was d\u00fcrfen andere damit machen? Wie kann ich mich sch\u00fctzen? Diese und viele andere Fragen werden kompetent und pr\u00e4zise bei&nbsp;<a href=\"http:\/\/www.datenparty.de\/\">&#8218;Datenparty&#8216;<\/a>&nbsp;erkl\u00e4rt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch das Chatten \u00fcbers Internet ist heute kaum noch wegzudenken. Viele Jugendliche sind hierbei aber sehr leichtsinnig und reden viel zu arglos mit Unbekannten. Einen Leitfaden f\u00fcrs sichere Chatten finden Sie&nbsp;<a href=\"http:\/\/www.jugendschutz.net\/\">HIER<\/a>.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informationen zum Thema Medien, Gewaltvideos auf Sch\u00fclerhandys, Spiele, Internet usw. findet man&nbsp;HIER. Hilfe von Jugendlichen f\u00fcr Jugendliche: das bietet&nbsp;Juuuport.Bei Online-Problemen (wie z. B. Cybermobbing, Datenklau oder Onlinesucht) helfen speziell geschulte Medienscouts Jugendlichen weiter. Die Seite&nbsp;&#8218;Klicksafe&#8216;&nbsp;bietet Tipps sowie aktuelle Informationen zu Chancen und Risiken der Internetnutzung. Es gibt Materialien f\u00fcr den Unterricht oder f\u00fcr Elternabende. Zudem werden kurze Filmspots angeboten, u.a. &#8222;Wo ist Klaus?&#8220; Viele Eltern beklagen, dass ihnen das n\u00f6tige Hintergrundwissen fehlt, um bei Gespr\u00e4chen rund ums Thema Internet mitreden&hellip; <a class=\"continue\" href=\"https:\/\/wordpress.nibis.de\/gymoedeme\/sicherheit-fuer-ihre-kinder-unsere-schuelerschaft-im-netz\/\">Weiterlesen:<span> Sicherheit f\u00fcr Ihre Kinder &#8211; unsere Sch\u00fclerschaft im Netz<\/span><\/a><\/p>\n","protected":false},"author":1411,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[83],"tags":[],"class_list":["post-1207","post","type-post","status-publish","format-standard","hentry","category-praevention"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/posts\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/users\/1411"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/comments?post=1207"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/posts\/1207\/revisions"}],"predecessor-version":[{"id":1208,"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/posts\/1207\/revisions\/1208"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/media?parent=1207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/categories?post=1207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/gymoedeme\/wp-json\/wp\/v2\/tags?post=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}