{"id":1078,"date":"2024-02-04T09:14:44","date_gmt":"2024-02-04T08:14:44","guid":{"rendered":"https:\/\/wordpress.nibis.de\/kgssalzh\/?p=1078"},"modified":"2024-02-04T09:14:44","modified_gmt":"2024-02-04T08:14:44","slug":"vom-singenden-springende-loeweneckerchen-bis-zur-bunten-katze-war-alles-dabei","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/kgssalzh\/vom-singenden-springende-loeweneckerchen-bis-zur-bunten-katze-war-alles-dabei\/","title":{"rendered":"Vom singenden, springende L\u00f6weneckerchen bis zur bunten Katze war alles dabei"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Diese M\u00e4rchen waren den rund 150 Sch\u00fclern und Sch\u00fclerinnen des f\u00fcnften Jahrgangs der KGS Salzhemmendorf bisher noch unbekannt. Umso gespannter lauschten sie den Blockfl\u00f6tenkl\u00e4ngen und Erz\u00e4hlungen zu den Br\u00fcdern Grimm erz\u00e4hlt von Olaf Steinl (https:\/\/erzaehlstrom.de\/), der als M\u00e4rchenerz\u00e4hler den F\u00fcnftkl\u00e4sslern das Besondere von M\u00e4rchen n\u00e4herbrachte. Die hinter ihm aufgebaute Leinwand zeigte die noch jungen Br\u00fcder Grimm, die in ihrer Sammlung u.a. das M\u00e4rchen \u201eDas singenden, springende L\u00f6weneckerchen\u201c niederschrieben. Neben der unterrichtlichen Thematisierung konnten die Sch\u00fclerInnen live ein m\u00fcndlich \u00fcbermitteltes M\u00e4rchen verfolgen und feststellen, welche M\u00e4rchenmerkmale ihnen bereits bekannt waren. Durch die lebhafte Erz\u00e4hlung, verschiedensten Interaktionen und mit viel Motivation zog er alle in seinen Bann. Eine gelungene Veranstaltung in Weihnachtszeit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese M\u00e4rchen waren den rund 150 Sch\u00fclern und Sch\u00fclerinnen des f\u00fcnften Jahrgangs der KGS Salzhemmendorf bisher noch unbekannt. Umso gespannter lauschten sie den Blockfl\u00f6tenkl\u00e4ngen und &hellip; <\/p>\n","protected":false},"author":9194300,"featured_media":1079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutsch"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/1078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/users\/9194300"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/comments?post=1078"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/1078\/revisions"}],"predecessor-version":[{"id":1080,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/1078\/revisions\/1080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media\/1079"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media?parent=1078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/categories?post=1078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/tags?post=1078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}