{"id":2330,"date":"2025-02-14T08:53:55","date_gmt":"2025-02-14T07:53:55","guid":{"rendered":"https:\/\/wordpress.nibis.de\/kgssalzh\/?p=2330"},"modified":"2025-02-16T19:00:51","modified_gmt":"2025-02-16T18:00:51","slug":"zukunftstag-2025","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/kgssalzh\/zukunftstag-2025\/","title":{"rendered":"Zukunftstag 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sehr geehrte Damen und Herren,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">am 03. April 2025 ist es wieder soweit &#8211; der Zukunftstag findet statt! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Zukunftstag wird in jedem Schuljahr an allen allgemeinbildenden Schulen durchgef\u00fchrt. Dies wird durch den Erlass \u201eBerufliche Orientierung an allgemeinbildenden Schulen\u201c vorgegeben. Sch\u00fclerInnen in Niedersachsen erhalten an diesem Aktionstag Einblicke in verschiedene Berufe, die geeignet sind, das traditionelle, geschlechtsspezifisch gepr\u00e4gte Spektrum m\u00f6glicher Berufe f\u00fcr M\u00e4dchen und Jungen zu erweitern. Sie k\u00f6nnen an Aktionen in Betrieben, Hochschulen und Einrichtungen teilnehmen und sollen so Berufe erkunden, die sie selbst meist nicht in Betracht ziehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Informationen finden Sie unter:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.girls-day.de\">https:\/\/www.girls-day.de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.boys-day.de\">https:\/\/www.boys-day.de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da am 03. April 2025 eine schulinterne Lehrerfortbildung durchgef\u00fchrt wird, findet an diesem Tag in der Sekundarstufe I (5. &#8211; 10. Jahrg\u00e4nge) kein Unterricht sowie keine Betreuung statt. Wir empfehlen den Sch\u00fclerInnen aller Schulzweige einen Betrieb nachzuweisen, in dem sie den Zukunftstag verbringen. Sch\u00fclerInnen ohne einen Platz bekommen Arbeitsauftr\u00e4ge von ihren Fachlehrkr\u00e4ften, die sie dann im Homeschooling erledigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich m\u00f6chte Sie bitten, Ihr Kind bei der Wahl eines Berufsbildes zu unterst\u00fctzen. Der Nachweis des aufnehmenden Betriebes muss sp\u00e4testens am 28. M\u00e4rz 2025 bei der Klassenleitung vorliegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Formular hierzu kann man hier runterladen:<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2025\/02\/Teilnahmebesta\u0308tigung-und-Teilnahmebescheinigung-\u2013-Zukunftstag-.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Einbettung von Einbettung von Teilnahmebesta\u0308tigung-und-Teilnahmebescheinigung-\u2013-Zukunftstag-..\"><\/object><a id=\"wp-block-file--media-cd6db992-63a0-4410-a485-73bfed305707\" href=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2025\/02\/Teilnahmebesta\u0308tigung-und-Teilnahmebescheinigung-\u2013-Zukunftstag-.pdf\">Teilnahmebesta\u0308tigung-und-Teilnahmebescheinigung-\u2013-Zukunftstag-<\/a><a href=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2025\/02\/Teilnahmebesta\u0308tigung-und-Teilnahmebescheinigung-\u2013-Zukunftstag-.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-cd6db992-63a0-4410-a485-73bfed305707\">Herunterladen<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Koops und Fr. Niemeyer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sehr geehrte Damen und Herren, am 03. April 2025 ist es wieder soweit &#8211; der Zukunftstag findet statt! Der Zukunftstag wird in jedem Schuljahr an &hellip; <\/p>\n","protected":false},"author":9194300,"featured_media":1060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,19],"tags":[],"class_list":["post-2330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-awt"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/2330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/users\/9194300"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/comments?post=2330"}],"version-history":[{"count":5,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/2330\/revisions"}],"predecessor-version":[{"id":2355,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/2330\/revisions\/2355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media\/1060"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media?parent=2330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/categories?post=2330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/tags?post=2330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}