{"id":5638,"date":"2026-05-07T15:35:26","date_gmt":"2026-05-07T13:35:26","guid":{"rendered":"https:\/\/wordpress.nibis.de\/kgssalzh\/?p=5638"},"modified":"2026-05-07T15:35:52","modified_gmt":"2026-05-07T13:35:52","slug":"krankenhaus-lindenbrunn-und-kgs-salzhemmendorf-starten-projekt-zurberufsorientierung-im-gesundheitswesen","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/kgssalzh\/krankenhaus-lindenbrunn-und-kgs-salzhemmendorf-starten-projekt-zurberufsorientierung-im-gesundheitswesen\/","title":{"rendered":"Krankenhaus Lindenbrunn und KGS Salzhemmendorf starten Projekt zur Berufsorientierung im Gesundheitswesen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Coppenbr\u00fcgge \/ Salzhemmendorf, 02.04.2026. Das Krankenhaus Lindenbrunn und die<br>Kooperative Gesamtschule (KGS) Salzhemmendorf arbeiten k\u00fcnftig enger zusammen, um<br>Sch\u00fclerinnen und Sch\u00fclern praxisnahe Einblicke in Gesundheits- und Pflegeberufe zu<br>erm\u00f6glichen. Die Zusammenarbeit findet im Rahmen des Projekts \u201eCare HaPy\u201c statt, das von<br>der Gesundheitsregion Hameln-Pyrmont gef\u00f6rdert wird. Das Krankenhaus Lindenbrunn und die<br>KGS Salzhemmendorf hatten sich zuvor gemeinsam erfolgreich im Rahmen einer Ausschreibung<br>um eine Anschubfinanzierung beworben. Pflege- und Gesundheitseinrichtungen aus dem<br>Landkreis Hameln-Pyrmont konnten daf\u00fcr ein F\u00f6rderkonzept einreichen. Die Gesundheitsregion<br>Hameln-Pyrmont w\u00e4hlte anschlie\u00dfend die Einrichtungen aus, deren Projektideen besonders<br>\u00fcberzeugten.<br>Ziel des Projekts ist es, junge Menschen fr\u00fchzeitig f\u00fcr Berufe im Gesundheitswesen zu<br>begeistern und ihnen realistische Einblicke in den Arbeitsalltag zu erm\u00f6glichen. Gleichzeitig soll<br>das Projekt dazu beitragen, dem zunehmenden Fachkr\u00e4ftemangel im Pflege- und<br>Gesundheitsbereich entgegenzuwirken.<br>Im Rahmen der Kooperation sind verschiedene Ma\u00dfnahmen geplant. Dazu geh\u00f6ren unter<br>anderem Betriebsbesichtigungen im Krankenhaus Lindenbrunn, Praktika, Workshops sowie<br>Gespr\u00e4che mit Mitarbeitenden und Auszubildenden. Besonders wichtig ist dabei der Austausch<br>auf Augenh\u00f6he: Auch Auszubildende und junge Fachkr\u00e4fte sollen ihre Erfahrungen mit den<br>Sch\u00fclerinnen und Sch\u00fclern teilen.<br>\u201eDer Gesundheitsbereich bietet vielf\u00e4ltige, sinnstiftende und zukunftssichere<br>Berufsm\u00f6glichkeiten. Mit dem Projekt m\u00f6chten wir jungen Menschen zeigen, wie<br>abwechslungsreich und erf\u00fcllend die Arbeit im Gesundheitswesen sein kann\u201c, erkl\u00e4rt Gerrit<br>Hirsch, Klinikmanager des Krankenhaus Lindenbrunn.<br>Auch an der KGS Salzhemmendorf wird die Kooperation sehr begr\u00fc\u00dft. \u201eBerufsorientierung lebt<br>von praktischen Erfahrungen. Die Zusammenarbeit mit dem Krankenhaus Lindenbrunn er\u00f6ffnet<br>unseren Sch\u00fclerinnen und Sch\u00fclern wertvolle Einblicke in einen wichtigen und vielseitigen<br>Berufszweig\u201c, sagt Gesamtschuldirektor Michael Ehrhardt.<br>Das Projekt ist auf eine l\u00e4ngerfristige Zusammenarbeit ausgelegt. Durch regelm\u00e4\u00dfige Angebote<br>sollen Sch\u00fclerinnen und Sch\u00fcler \u00fcber einen l\u00e4ngeren Zeitraum hinweg begleitet und bei ihrer<br>beruflichen Orientierung unterst\u00fctzt werden.<br>Die F\u00f6rderung erfolgt durch die Gesundheitsregion Hameln-Pyrmont, die mit dem Projekt \u201eCare<br>HaPy\u201c gezielt Initiativen unterst\u00fctzt, die junge Menschen f\u00fcr Ausbildungs- und<br>Berufsm\u00f6glichkeiten im Gesundheitswesen gewinnen m\u00f6chten. Weitere Informationen zum<br>Projekt finden Sie unter www.gesundheitsregion.hameln-pyrmont.de\/carehapy\/.<br>V. l. n. r: Catharina Reiche (Referentin f\u00fcr Recruiting Krankenhaus Lindenbrunn), Gerrit Hirsch<br>(Klinikmanager Krankenhaus Lindenbrunn), Michael Ehrhardt (Gesamtschuldirektor KGS<br>Salzhemmendorf) und Sabrina Niemeyer (Fachbereichsleiterin f\u00fcr Arbeit-Wirtschaft-Technik \/<br>Berufsorientierung KGS Salzhemmendorf) bei der Unterschrift des Letter of Intent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coppenbr\u00fcgge \/ Salzhemmendorf, 02.04.2026. Das Krankenhaus Lindenbrunn und dieKooperative Gesamtschule (KGS) Salzhemmendorf arbeiten k\u00fcnftig enger zusammen, umSch\u00fclerinnen und Sch\u00fclern praxisnahe Einblicke in Gesundheits- und Pflegeberufe &hellip; <\/p>\n","protected":false},"author":9194300,"featured_media":5639,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/5638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/users\/9194300"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/comments?post=5638"}],"version-history":[{"count":2,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/5638\/revisions"}],"predecessor-version":[{"id":5642,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/5638\/revisions\/5642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media\/5639"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media?parent=5638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/categories?post=5638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/tags?post=5638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}