{"id":5790,"date":"2026-06-23T18:21:53","date_gmt":"2026-06-23T16:21:53","guid":{"rendered":"https:\/\/wordpress.nibis.de\/kgssalzh\/?p=5790"},"modified":"2026-06-23T18:22:49","modified_gmt":"2026-06-23T16:22:49","slug":"ein-blick-hinter-die-kulissen-wo-theorie-auf-echte-praxis-trifft","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/kgssalzh\/ein-blick-hinter-die-kulissen-wo-theorie-auf-echte-praxis-trifft\/","title":{"rendered":"Ein Blick hinter die Kulissen: Wo Theorie auf echte Praxis trifft"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der WPK Gesundheit und Soziales 9R zu Gast im Krankenhaus Lindenbrunn<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie sieht der Alltag in einem modernen Krankenhaus wirklich aus? Dieser Frage ging unser WPB Kurs \u201eGesundheit und Soziales\u201c bei einem spannenden Exkursionstag nach. Schon beim Betreten des Hauses wurden wir mit einer herzlichen und gastfreundlichen Begr\u00fc\u00dfung&nbsp;empfangen, die sofort f\u00fcr eine offene Atmosph\u00e4re sorgte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bevor es in die Praxis ging, warfen wir einen Blick zur\u00fcck: Ein kurzer geschichtlicher R\u00fcckblick verdeutlichte uns den beeindruckenden Wandel des Krankenhauses \u2013 von den Anf\u00e4ngen als Sanatorium bis hin zum hochmodernen medizinischen Dienstleistungszentrum von heute.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Anschlie\u00dfend hie\u00df es: Rein ins Geschehen! In verschiedenen Fachabteilungen erhielten wir tiefe Einblicke in medizinische und pflegerische Abl\u00e4ufe. Besonders spannend war der Gang \u00fcber die Stationen<strong>, &nbsp;<\/strong>bei dem wir den direkten Kontakt zum Klinikalltag erlebten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Zum Abschluss des Tages nahmen wir uns Zeit f\u00fcr eine gemeinsame Reflexion: Passt die \u201eWelt des Krankenhauses\u201c zu mir? Welche Berufe haben mich besonders beeindruckt? Die R\u00fcckmeldungen waren durchweg positiv und haben bei vielen das Interesse an einer beruflichen Zukunft im Gesundheitswesen geweckt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach diesem ereignisreichen Tag ist die Vorfreude gro\u00df: Wir blicken nun gespannt auf die kommenden Fachpraxistage in der Schule, um unsere Einblicke zu vertiefen, und freuen uns schon jetzt auf das Praktikum im n\u00e4chsten Schuljahr,&nbsp;in dem wir dann selbst aktiv mit anpacken d\u00fcrfen!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5791\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-9-800x675.jpg\" alt=\"\" class=\"wp-image-5791\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5793\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-8-800x675.jpg\" alt=\"\" class=\"wp-image-5793\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5792\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-1-800x675.jpg\" alt=\"\" class=\"wp-image-5792\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5795\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-7-800x675.jpg\" alt=\"\" class=\"wp-image-5795\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5796\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-6-800x675.jpg\" alt=\"\" class=\"wp-image-5796\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5797\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-5-800x675.jpg\" alt=\"\" class=\"wp-image-5797\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5794\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-4-800x675.jpg\" alt=\"\" class=\"wp-image-5794\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5798\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-3-800x675.jpg\" alt=\"\" class=\"wp-image-5798\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"675\" data-id=\"5799\" src=\"https:\/\/wordpress.nibis.de\/kgssalzh\/files\/2026\/06\/2026-05-04-Lindenbrunnbesuch-2-800x675.jpg\" alt=\"\" class=\"wp-image-5799\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Der WPK Gesundheit und Soziales 9R zu Gast im Krankenhaus Lindenbrunn Wie sieht der Alltag in einem modernen Krankenhaus wirklich aus? Dieser Frage ging unser &hellip; <\/p>\n","protected":false},"author":9194300,"featured_media":5798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,16],"tags":[],"class_list":["post-5790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-ethik"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/5790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/users\/9194300"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/comments?post=5790"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/5790\/revisions"}],"predecessor-version":[{"id":5800,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/posts\/5790\/revisions\/5800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media\/5798"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/media?parent=5790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/categories?post=5790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/kgssalzh\/wp-json\/wp\/v2\/tags?post=5790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}