{"id":704,"date":"2022-12-07T15:21:00","date_gmt":"2022-12-07T14:21:00","guid":{"rendered":"https:\/\/wordpress.nibis.de\/knieberg\/?p=704"},"modified":"2023-02-17T09:23:57","modified_gmt":"2023-02-17T08:23:57","slug":"der-nikolaus-zu-besuch-am-knieberg","status":"publish","type":"post","link":"https:\/\/wordpress.nibis.de\/knieberg\/der-nikolaus-zu-besuch-am-knieberg\/","title":{"rendered":"Der Nikolaus zu Besuch am Knieberg"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Endlich war es wieder so weit. Am 06.12.2022 kamen der Nikolaus und die Piraten in die Schule. Nikolaus, das ist ja klar, aber Piraten? Das sind die Piraten aus einer alten Geschichte. Dort wurden die Kinder von Myra, das liegt in der T\u00fcrkei, von Piraten gefangen und der Nikolaus konnte sie wieder befreien. Und genau so spielte es sich auch im Forum der Schule am Knieberg ab. Wilde singende Piraten\u2026 hoch auf den Wellen da reiten wir\u2026., gefangene Kinder und ein Nikolaus, der die Schw\u00e4che der Piraten kennt und sie mit Geld und Gold besticht und das Wertvollste, die Kinder, wieder befreit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Endlich war es wieder so weit. Am 06.12.2022 kamen der Nikolaus und die Piraten in die Schule. Nikolaus, das ist ja klar, aber Piraten? Das sind die Piraten aus einer alten Geschichte. Dort wurden die Kinder von Myra, das liegt in der T\u00fcrkei, von Piraten gefangen und der Nikolaus konnte sie wieder befreien. Und genau so spielte es sich auch im Forum der Schule am Knieberg ab. Wilde singende Piraten\u2026 hoch auf den Wellen da reiten wir\u2026., gefangene Kinder und&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/wordpress.nibis.de\/knieberg\/der-nikolaus-zu-besuch-am-knieberg\/\">Weiterlesen<span class=\"screen-reader-text\"> Weiterlesen<\/span><\/a><\/p>\n","protected":false},"author":9193665,"featured_media":705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,23,17],"tags":[],"class_list":["post-704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-feste-und-feiern","category-willkommen"],"_links":{"self":[{"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/posts\/704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/users\/9193665"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/comments?post=704"}],"version-history":[{"count":4,"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/posts\/704\/revisions"}],"predecessor-version":[{"id":728,"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/posts\/704\/revisions\/728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/media\/705"}],"wp:attachment":[{"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/media?parent=704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/categories?post=704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.nibis.de\/knieberg\/wp-json\/wp\/v2\/tags?post=704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}